{"id":282,"date":"2025-08-05T12:58:52","date_gmt":"2025-08-05T12:58:52","guid":{"rendered":"https:\/\/www.ideindus.com\/?page_id=282"},"modified":"2025-10-21T10:54:27","modified_gmt":"2025-10-21T10:54:27","slug":"industries","status":"publish","type":"page","link":"https:\/\/www.ideindus.com\/fr\/industries\/","title":{"rendered":"Industries"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"282\" class=\"elementor elementor-282\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db75c86 twbb_section twbb_full_h e-flex e-con-boxed e-con e-parent\" data-id=\"db75c86\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7,&quot;sizes&quot;:[]},&quot;background_motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01d3941 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial twbb-headline--style-rotate elementor-widget elementor-widget-twbbanimated-headline\" data-id=\"01d3941\" data-element_type=\"widget\" data-settings=\"{&quot;headline_style&quot;:&quot;rotate&quot;,&quot;rotating_text&quot;:&quot;Smart Solutions&quot;,&quot;animation_type&quot;:&quot;clip&quot;}\" data-widget_type=\"twbbanimated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <h1 class=\"twbb-headline twbb-headline-animation-type-clip\">\n        <span class=\"twbb-headline-dynamic-wrapper twbb-headline-text-wrapper\"><\/span>\n          <span class=\"twbb-headline-plain-text twbb-headline-text-wrapper\"> pour chaque secteur d'activit\u00e9<\/span>\n        <\/h1>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bba9f1 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"8bba9f1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Chez ideindus, nous comprenons que chaque industrie a des d\u00e9fis et des exigences uniques. Nos solutions IoT sont con\u00e7ues pour \u00eatre hautement adaptables, offrant des capacit\u00e9s de surveillance en temps r\u00e9el et de maintenance pr\u00e9dictive adapt\u00e9es \u00e0 vos besoins op\u00e9rationnels sp\u00e9cifiques. Nous vous donnons les moyens d'optimiser les performances, de r\u00e9duire les temps d'arr\u00eat et de prolonger la dur\u00e9e de vie des \u00e9quipements.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d4e0df0 e-con-full e-flex e-con e-child\" data-id=\"d4e0df0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02952ab elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"02952ab\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d409b20 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"d409b20\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-mj5fgdf4 twbb_section twbb_hero_19 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"mj5fgdf4\" data-element_type=\"container\" id=\"Auto_section\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-givhlk3f elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"givhlk3f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1121\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-kjo8z2jo e-con-full e-flex e-con e-child\" data-id=\"kjo8z2jo\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47584d9 elementor-widget elementor-widget-heading\" data-id=\"47584d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Optimiser l'efficacit\u00e9 <em>dans le secteur automobile<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-wxnlhlrr elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"wxnlhlrr\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous aidons les constructeurs automobiles \u00e0 r\u00e9duire les temps d'arr\u00eat impr\u00e9vus, \u00e0 surveiller les lignes de production en temps r\u00e9el et \u00e0 garantir une grande fiabilit\u00e9 op\u00e9rationnelle gr\u00e2ce \u00e0 des technologies de maintenance pr\u00e9dictive.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-w8rh17un e-con-full e-flex e-con e-child\" data-id=\"w8rh17un\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-zrvm6hmg elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"zrvm6hmg\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7b0045 twbb_section twbb_hero_19 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"e7b0045\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9de2c13 e-con-full e-flex e-con e-child\" data-id=\"9de2c13\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ec515f elementor-widget elementor-widget-heading\" data-id=\"8ec515f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Optimiser l'efficacit\u00e9 <em>dans le secteur automobile<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e276a1d elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"e276a1d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1121\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47144d7 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"47144d7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous aidons les constructeurs automobiles \u00e0 r\u00e9duire les temps d'arr\u00eat impr\u00e9vus, \u00e0 surveiller les lignes de production en temps r\u00e9el et \u00e0 garantir une grande fiabilit\u00e9 op\u00e9rationnelle gr\u00e2ce \u00e0 des technologies de maintenance pr\u00e9dictive.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c6e1a7c e-con-full e-flex e-con e-child\" data-id=\"c6e1a7c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ab874a5 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"ab874a5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f8868c2 twbb_section twbb_hero_19 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"f8868c2\" data-element_type=\"container\" id=\"Energy_section\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-83e5962 e-con-full e-flex e-con e-child\" data-id=\"83e5962\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f3a883e elementor-widget elementor-widget-heading\" data-id=\"f3a883e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Assurer la fiabilit\u00e9 <em>dans le domaine de l'\u00e9nergie<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ac4ea8 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"5ac4ea8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Qu'il s'agisse de centrales traditionnelles ou de sources renouvelables, nos solutions optimisent les performances des \u00e9quipements, r\u00e9duisent les pannes et prolongent la dur\u00e9e de vie des actifs dans le secteur de l'\u00e9nergie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-80b5848 e-con-full e-flex e-con e-child\" data-id=\"80b5848\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-357656d elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"357656d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6be1464 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"6be1464\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1120\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b0525a twbb_section twbb_hero_19 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"6b0525a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f7c7f51 e-con-full e-flex e-con e-child\" data-id=\"f7c7f51\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd969e4 elementor-widget elementor-widget-heading\" data-id=\"fd969e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Assurer la fiabilit\u00e9 <em>dans le domaine de l'\u00e9nergie<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9f97fa elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"d9f97fa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1120\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/wind-turbines-night-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e7a9ef elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"7e7a9ef\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Qu'il s'agisse de centrales traditionnelles ou de sources renouvelables, nos solutions optimisent les performances des \u00e9quipements, r\u00e9duisent les pannes et prolongent la dur\u00e9e de vie des actifs dans le secteur de l'\u00e9nergie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-edd044c e-con-full e-flex e-con e-child\" data-id=\"edd044c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0c598e elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"e0c598e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67cefc0 twbb_section twbb_hero_19 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"67cefc0\" data-element_type=\"container\" id=\"Manu_section\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6eef484 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"6eef484\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1119\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ef0296 e-con-full e-flex e-con e-child\" data-id=\"7ef0296\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa51bf6 elementor-widget elementor-widget-heading\" data-id=\"aa51bf6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Manufacture intelligente\n<em>\u00e0 grande \u00e9chelle<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bccf51d elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"bccf51d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous permettons aux fabricants de passer de strat\u00e9gies r\u00e9actives \u00e0 des strat\u00e9gies pr\u00e9dictives, en am\u00e9liorant l'efficacit\u00e9, en r\u00e9duisant les pannes et en am\u00e9liorant la planification de la production.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5aa0e8 e-con-full e-flex e-con e-child\" data-id=\"d5aa0e8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66b1933 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"66b1933\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a95983d twbb_section twbb_hero_19 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"a95983d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0dbc723 e-con-full e-flex e-con e-child\" data-id=\"0dbc723\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e11db0 elementor-widget elementor-widget-heading\" data-id=\"9e11db0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Manufacture intelligente <font color=\"#1b1e3e\"><i>\u00e0 grande \u00e9chelle<\/i><\/font><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf67d82 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"bf67d82\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1119\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metallic-robot-arm-modern-steel-factory-generated-by-ai-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfa7bb6 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"dfa7bb6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous permettons aux fabricants de passer de strat\u00e9gies r\u00e9actives \u00e0 des strat\u00e9gies pr\u00e9dictives, en am\u00e9liorant l'efficacit\u00e9, en r\u00e9duisant les pannes et en am\u00e9liorant la planification de la production.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1e208d e-con-full e-flex e-con e-child\" data-id=\"d1e208d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6ef8df elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"f6ef8df\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e67f62 twbb_section twbb_hero_19 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"5e67f62\" data-element_type=\"container\" id=\"Healthcare_section\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bc52b5e e-con-full e-flex e-con e-child\" data-id=\"bc52b5e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ccbbc9 elementor-widget elementor-widget-heading\" data-id=\"9ccbbc9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Assurer la disponibilit\u00e9 <em>dans le domaine de la sant\u00e9<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86dba08 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"86dba08\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous soutenons les \u00e9tablissements de sant\u00e9 en veillant \u00e0 ce que leurs \u00e9quipements critiques fonctionnent de mani\u00e8re fiable, ce qui permet d'\u00e9viter les pannes et de maintenir des soins ininterrompus aux patients.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59c26d4 e-con-full e-flex e-con e-child\" data-id=\"59c26d4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8dbab05 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"8dbab05\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1112743 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"1112743\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1118\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d78f954 twbb_section twbb_hero_19 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"d78f954\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a23d06c e-con-full e-flex e-con e-child\" data-id=\"a23d06c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c10c015 elementor-widget elementor-widget-heading\" data-id=\"c10c015\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Assurer la disponibilit\u00e9 <em>dans le domaine de la sant\u00e9<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d603795 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"d603795\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1118\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/logo_make_11_06_2023_401-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d9b80a elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3d9b80a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous soutenons les \u00e9tablissements de sant\u00e9 en veillant \u00e0 ce que leurs \u00e9quipements critiques fonctionnent de mani\u00e8re fiable, ce qui permet d'\u00e9viter les pannes et de maintenir des soins ininterrompus aux patients.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d154404 e-con-full e-flex e-con e-child\" data-id=\"d154404\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8091a8 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"a8091a8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a09ff64 twbb_section twbb_hero_19 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"a09ff64\" data-element_type=\"container\" id=\"Logistics_section\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6997df0 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"6997df0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1116\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b8b630 e-con-full e-flex e-con e-child\" data-id=\"1b8b630\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2471576 elementor-widget elementor-widget-heading\" data-id=\"2471576\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La fiabilit\u00e9 en mouvement <font color=\"#1b1e3e\"><i>pour la logistique<\/i><\/font><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1af4055 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1af4055\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous aidons les op\u00e9rations logistiques en surveillant les pi\u00e8ces mobiles critiques, en am\u00e9liorant la maintenance de la flotte, la fiabilit\u00e9 de l'automatisation des entrep\u00f4ts et le temps de disponibilit\u00e9 des livraisons.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f5fb388 e-con-full e-flex e-con e-child\" data-id=\"f5fb388\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18d42fe elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"18d42fe\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-534103f twbb_section twbb_hero_19 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"534103f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dc8885a e-con-full e-flex e-con e-child\" data-id=\"dc8885a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fb8b0b elementor-widget elementor-widget-heading\" data-id=\"2fb8b0b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La fiabilit\u00e9 en mouvement <font color=\"#1b1e3e\"><i>pour la logistique<\/i><\/font><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5efff25 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"5efff25\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1116\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-concept-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a06409 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"8a06409\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous aidons les op\u00e9rations logistiques en surveillant les pi\u00e8ces mobiles critiques, en am\u00e9liorant la maintenance de la flotte, la fiabilit\u00e9 de l'automatisation des entrep\u00f4ts et le temps de disponibilit\u00e9 des livraisons.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-87fb9e2 e-con-full e-flex e-con e-child\" data-id=\"87fb9e2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97b7c13 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"97b7c13\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1034d82 twbb_section twbb_hero_19 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"1034d82\" data-element_type=\"container\" id=\"OilGas_section\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d572a22 e-con-full e-flex e-con e-child\" data-id=\"d572a22\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dcd7ee7 elementor-widget elementor-widget-heading\" data-id=\"dcd7ee7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Extraire de la valeur <em>in Oil &amp; Gas<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54d8f18 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"54d8f18\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"133\" data-end=\"434\">Nous permettons aux op\u00e9rateurs p\u00e9troliers et gaziers de surveiller les \u00e9quipements critiques, de pr\u00e9venir les pannes et d'optimiser les op\u00e9rations d'extraction et de traitement gr\u00e2ce \u00e0 des solutions avanc\u00e9es de maintenance pr\u00e9dictive.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0dcc743 e-con-full e-flex e-con e-child\" data-id=\"0dcc743\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec49ff6 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"ec49ff6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7f1d79 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"d7f1d79\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-scaled.jpg\" class=\"attachment-full size-full wp-image-297\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-scaled.jpg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-300x200.jpg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-1024x683.jpg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-768x512.jpg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-1536x1024.jpg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-2048x1365.jpg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ecfc9fc twbb_section twbb_hero_19 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"ecfc9fc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c28ae82 e-con-full e-flex e-con e-child\" data-id=\"c28ae82\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bdb97ad elementor-widget elementor-widget-heading\" data-id=\"bdb97ad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Extraire de la valeur <em>in Oil &amp; Gas<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63b9406 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"63b9406\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-scaled.jpg\" class=\"attachment-full size-full wp-image-297\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-scaled.jpg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-300x200.jpg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-1024x683.jpg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-768x512.jpg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-1536x1024.jpg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-2048x1365.jpg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/view-male-engineer-work-engineers-day-celebration-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c107d4 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"5c107d4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"133\" data-end=\"434\">Nous permettons aux op\u00e9rateurs p\u00e9troliers et gaziers de surveiller les \u00e9quipements critiques, de pr\u00e9venir les pannes et d'optimiser les op\u00e9rations d'extraction et de traitement gr\u00e2ce \u00e0 des solutions avanc\u00e9es de maintenance pr\u00e9dictive.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a9310f9 e-con-full e-flex e-con e-child\" data-id=\"a9310f9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8499a1 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"f8499a1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75d6150 twbb_section twbb_hero_19 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"75d6150\" data-element_type=\"container\" id=\"Chemistry_section\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e37f792 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"e37f792\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1111\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12aaef5 e-con-full e-flex e-con e-child\" data-id=\"12aaef5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71694c9 elementor-widget elementor-widget-heading\" data-id=\"71694c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">More innovation <em>en chimie<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17d50c3 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"17d50c3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nos solutions aident les fabricants de produits chimiques \u00e0 maintenir la s\u00e9curit\u00e9, \u00e0 am\u00e9liorer l'efficacit\u00e9 des processus et \u00e0 r\u00e9duire les arr\u00eats impr\u00e9vus et co\u00fbteux gr\u00e2ce \u00e0 la surveillance en temps r\u00e9el et \u00e0 l'analyse pr\u00e9dictive.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-85b6bd1 e-con-full e-flex e-con e-child\" data-id=\"85b6bd1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f37930c elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"f37930c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-969e656 twbb_section twbb_hero_19 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"969e656\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8b9bd99 e-con-full e-flex e-con e-child\" data-id=\"8b9bd99\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7a4b9f elementor-widget elementor-widget-heading\" data-id=\"c7a4b9f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Catalyzing Innovation <em>en chimie<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d552abc elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"d552abc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1111\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/world-science-day-research-innovation-elements-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67d08c8 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"67d08c8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nos solutions aident les fabricants de produits chimiques \u00e0 maintenir la s\u00e9curit\u00e9, \u00e0 am\u00e9liorer l'efficacit\u00e9 des processus et \u00e0 r\u00e9duire les arr\u00eats impr\u00e9vus et co\u00fbteux gr\u00e2ce \u00e0 la surveillance en temps r\u00e9el et \u00e0 l'analyse pr\u00e9dictive.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e996b04 e-con-full e-flex e-con e-child\" data-id=\"e996b04\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-297fc54 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"297fc54\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75f2e26 twbb_section twbb_hero_19 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"75f2e26\" data-element_type=\"container\" id=\"Mining_section\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-36e4bae e-con-full e-flex e-con e-child\" data-id=\"36e4bae\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62eb72a elementor-widget elementor-widget-heading\" data-id=\"62eb72a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Creuser plus intelligemment <em>dans l\u2019exploitation mini\u00e8re<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1db08e5 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1db08e5\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous aidons les exploitations mini\u00e8res \u00e0 am\u00e9liorer le temps de fonctionnement des machines, \u00e0 r\u00e9duire les risques op\u00e9rationnels et \u00e0 maximiser l'extraction des ressources gr\u00e2ce \u00e0 la maintenance pr\u00e9dictive et \u00e0 la surveillance de l'\u00e9tat des machines.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48bf78a e-con-full e-flex e-con e-child\" data-id=\"48bf78a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32ed7ec elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"32ed7ec\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-389b928 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"389b928\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1112\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-741b910 twbb_section twbb_hero_19 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"741b910\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d6e5343 e-con-full e-flex e-con e-child\" data-id=\"d6e5343\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ebce6a elementor-widget elementor-widget-heading\" data-id=\"0ebce6a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Creuser plus intelligemment <em>dans l\u2019exploitation mini\u00e8re<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec8b4c9 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"ec8b4c9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-1112\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/portrait-engineers-work-hours-job-site-1-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-557e20b elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"557e20b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous aidons les exploitations mini\u00e8res \u00e0 am\u00e9liorer le temps de fonctionnement des machines, \u00e0 r\u00e9duire les risques op\u00e9rationnels et \u00e0 maximiser l'extraction des ressources gr\u00e2ce \u00e0 la maintenance pr\u00e9dictive et \u00e0 la surveillance de l'\u00e9tat des machines.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a6ea76 e-con-full e-flex e-con e-child\" data-id=\"3a6ea76\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d95ddf elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6d95ddf\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49b3045 twbb_section twbb_hero_19 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"49b3045\" data-element_type=\"container\" id=\"Food_section\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7095980 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"7095980\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-871\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b6bbdd e-con-full e-flex e-con e-child\" data-id=\"5b6bbdd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec57c5a elementor-widget elementor-widget-heading\" data-id=\"ec57c5a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Assurer la fra\u00eecheur <em>dans l'industrie alimentaire<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b6d0c3 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"2b6d0c3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nos technologies aident les producteurs de denr\u00e9es alimentaires \u00e0 maintenir la fiabilit\u00e9 de leurs \u00e9quipements, \u00e0 garantir le respect des normes de s\u00e9curit\u00e9 et \u00e0 minimiser les interruptions de production afin de fournir des produits de haute qualit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee72835 e-con-full e-flex e-con e-child\" data-id=\"ee72835\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9fbc0cb elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"9fbc0cb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-94ad977 twbb_section twbb_hero_19 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"94ad977\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e8cef2d e-con-full e-flex e-con e-child\" data-id=\"e8cef2d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f58a049 elementor-widget elementor-widget-heading\" data-id=\"f58a049\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Assurer la fra\u00eecheur <em>dans l'industrie alimentaire<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-111c015 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"111c015\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg\" class=\"attachment-full size-full wp-image-871\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1-300x200.jpeg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1-1024x683.jpeg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1-768x512.jpeg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1-1536x1024.jpeg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1-2048x1366.jpeg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/mechanic-controls-robotic-arm-futuristic-production-line-generated-by-ai-redimensionne-taille-2560x1707-1-600x400.jpeg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9e130e elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b9e130e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nos technologies aident les producteurs de denr\u00e9es alimentaires \u00e0 maintenir la fiabilit\u00e9 de leurs \u00e9quipements, \u00e0 garantir le respect des normes de s\u00e9curit\u00e9 et \u00e0 minimiser les interruptions de production afin de fournir des produits de haute qualit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a3d530 e-con-full e-flex e-con e-child\" data-id=\"1a3d530\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8df0525 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"8df0525\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b1a718d twbb_section twbb_hero_19 elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"b1a718d\" data-element_type=\"container\" id=\"Marine_section\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7e2310a e-con-full e-flex e-con e-child\" data-id=\"7e2310a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d6fefbf elementor-widget elementor-widget-heading\" data-id=\"d6fefbf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Plus de performance <em>dans le domaine maritime<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06f8bde elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"06f8bde\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous fournissons aux op\u00e9rateurs maritimes des outils de surveillance en temps r\u00e9el et de maintenance pr\u00e9dictive afin d'am\u00e9liorer la fiabilit\u00e9 des navires, de r\u00e9duire les temps d'arr\u00eat et d'optimiser les op\u00e9rations de la flotte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1cd5ab2 e-con-full e-flex e-con e-child\" data-id=\"1cd5ab2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b539c6 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"2b539c6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a7df45 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"1a7df45\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-scaled.jpg\" class=\"attachment-full size-full wp-image-913\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-scaled.jpg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-300x200.jpg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-1024x683.jpg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-768x512.jpg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-1536x1024.jpg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-2048x1365.jpg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0a82c34 twbb_section twbb_hero_19 elementor-hidden-desktop elementor-hidden-tablet e-flex e-con-boxed e-con e-parent\" data-id=\"0a82c34\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-139e7bc e-con-full e-flex e-con e-child\" data-id=\"139e7bc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38fce35 elementor-widget elementor-widget-heading\" data-id=\"38fce35\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Plus de performance <em>dans le domaine maritime<\/em><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a67896f elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"a67896f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-scaled.jpg\" class=\"attachment-full size-full wp-image-913\" alt=\"\" srcset=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-scaled.jpg 2560w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-300x200.jpg 300w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-1024x683.jpg 1024w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-768x512.jpg 768w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-1536x1024.jpg 1536w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-2048x1365.jpg 2048w, https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/transport-logistics-products-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40d2876 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"40d2876\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous fournissons aux op\u00e9rateurs maritimes des outils de surveillance en temps r\u00e9el et de maintenance pr\u00e9dictive afin d'am\u00e9liorer la fiabilit\u00e9 des navires, de r\u00e9duire les temps d'arr\u00eat et d'optimiser les op\u00e9rations de la flotte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b9a8ca3 e-con-full e-flex e-con e-child\" data-id=\"b9a8ca3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6672013 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6672013\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ideindus.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenir un aper\u00e7u<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dfc07f9 twbb_section e-con-full e-flex e-con e-parent\" data-id=\"dfc07f9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9423ee7 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget-tablet__width-initial twbb_cta-button-wrapper-center twbb_cta-valign-align-top twbb_cta-button-wrapper-center twbb_cta-button-wrapper-center twbb_cta-position-button-bottom twbb_cta-tablet-position-button-bottom twbb_cta-mobile-position-button-bottom elementor-invisible elementor-widget elementor-widget-twbb_call-to-action\" data-id=\"9423ee7\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"twbb_call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div  class=\"twbb_cta-wrapper\">\n      <div class=\"twbb_cta-content-wrapper\">\n    <div class=\"twbb_cta-content-inner\">\n                <h2 class=\"twbb_cta-title\">D\u00e9couvrez nos solutions innovantes<\/h2>\n                    <div class=\"twbb_cta-description\">D\u00e9couvrez comment les technologies IoT intelligentes d'IdeIndus peuvent transformer votre industrie gr\u00e2ce au suivi en temps r\u00e9el et \u00e0 la maintenance pr\u00e9dictive.<\/div>\n              <\/div>\n    <div class=\"twbb_cta-button-wrapper\">\n        <div class=\"twbb_cta-buttons\">\n              <div class=\"twbb_cta-button-item twbb_cta-button-item__one twbb_cta-button-enable-yes\">\n          <a href=\"https:\/\/outlook.office365.com\/book\/PagederservationIDEINDUS@md6.fr\/?ismsaljsauthenabled=true\" class=\"elementor-button twbb_cta-button elementor-size- twbb_cta-button__one\"            >R\u00e9server une d\u00e9monstration<\/a>\n        <\/div>\n                        <\/div>\n    <\/div>\n  <\/div>\n        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>for Every Industry At ideindus, we understand that each industry has unique challenges and requirements. Our IoT solutions are designed to be highly adaptable, providing real-time monitoring and predictive maintenance capabilities tailored to your specific operational needs. We empower you to optimize performance, reduce downtime, and extend equipment life. Learn More Get a Quote Driving [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-282","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Industries \u2013 Predictive Maintenance Solutions Across Sectors | ideindus<\/title>\n<meta name=\"description\" content=\"See how ideindus Predictive Maintenance solutions serve multiple industries, enabling smart monitoring, equipment reliability, and Industry 4.0 transformation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ideindus.com\/fr\/industries\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Industries \u2013 Predictive Maintenance Solutions Across Sectors | ideindus\" \/>\n<meta property=\"og:description\" content=\"See how ideindus Predictive Maintenance solutions serve multiple industries, enabling smart monitoring, equipment reliability, and Industry 4.0 transformation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ideindus.com\/fr\/industries\/\" \/>\n<meta property=\"og:site_name\" content=\"ideindus: Industrial IoT Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-21T10:54:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ideindus.com\/industries\/\",\"url\":\"https:\/\/www.ideindus.com\/industries\/\",\"name\":\"Industries \u2013 Predictive Maintenance Solutions Across Sectors | ideindus\",\"isPartOf\":{\"@id\":\"https:\/\/www.ideindus.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ideindus.com\/industries\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ideindus.com\/industries\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg\",\"datePublished\":\"2025-08-05T12:58:52+00:00\",\"dateModified\":\"2025-10-21T10:54:27+00:00\",\"description\":\"See how ideindus Predictive Maintenance solutions serve multiple industries, enabling smart monitoring, equipment reliability, and Industry 4.0 transformation.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ideindus.com\/industries\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ideindus.com\/industries\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ideindus.com\/industries\/#primaryimage\",\"url\":\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg\",\"contentUrl\":\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ideindus.com\/industries\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ideindus.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Industries\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ideindus.com\/#website\",\"url\":\"https:\/\/www.ideindus.com\/\",\"name\":\"ideindus: Industrial IoT Solutions\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ideindus.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ideindus.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ideindus.com\/#organization\",\"name\":\"ideindus: Industrial IoT Solutions\",\"url\":\"https:\/\/www.ideindus.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ideindus.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/cropped-cropped-ideindus-logo.jpg\",\"contentUrl\":\"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/cropped-cropped-ideindus-logo.jpg\",\"width\":1000,\"height\":364,\"caption\":\"ideindus: Industrial IoT Solutions\"},\"image\":{\"@id\":\"https:\/\/www.ideindus.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Industries \u2013 Predictive Maintenance Solutions Across Sectors | ideindus","description":"See how ideindus Predictive Maintenance solutions serve multiple industries, enabling smart monitoring, equipment reliability, and Industry 4.0 transformation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ideindus.com\/fr\/industries\/","og_locale":"fr_FR","og_type":"article","og_title":"Industries \u2013 Predictive Maintenance Solutions Across Sectors | ideindus","og_description":"See how ideindus Predictive Maintenance solutions serve multiple industries, enabling smart monitoring, equipment reliability, and Industry 4.0 transformation.","og_url":"https:\/\/www.ideindus.com\/fr\/industries\/","og_site_name":"ideindus: Industrial IoT Solutions","article_modified_time":"2025-10-21T10:54:27+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ideindus.com\/industries\/","url":"https:\/\/www.ideindus.com\/industries\/","name":"Industries \u2013 Predictive Maintenance Solutions Across Sectors | ideindus","isPartOf":{"@id":"https:\/\/www.ideindus.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ideindus.com\/industries\/#primaryimage"},"image":{"@id":"https:\/\/www.ideindus.com\/industries\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg","datePublished":"2025-08-05T12:58:52+00:00","dateModified":"2025-10-21T10:54:27+00:00","description":"See how ideindus Predictive Maintenance solutions serve multiple industries, enabling smart monitoring, equipment reliability, and Industry 4.0 transformation.","breadcrumb":{"@id":"https:\/\/www.ideindus.com\/industries\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ideindus.com\/industries\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ideindus.com\/industries\/#primaryimage","url":"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg","contentUrl":"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/metal-industry-workshop-modern-machinery-building-steel-parts-generated-by-ai-redimensionne-taille-2560x1707-1.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ideindus.com\/industries\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ideindus.com\/"},{"@type":"ListItem","position":2,"name":"Industries"}]},{"@type":"WebSite","@id":"https:\/\/www.ideindus.com\/#website","url":"https:\/\/www.ideindus.com\/","name":"ideindus: Industrial IoT Solutions","description":"","publisher":{"@id":"https:\/\/www.ideindus.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ideindus.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ideindus.com\/#organization","name":"ideindus: Industrial IoT Solutions","url":"https:\/\/www.ideindus.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ideindus.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/cropped-cropped-ideindus-logo.jpg","contentUrl":"https:\/\/www.ideindus.com\/wp-content\/uploads\/2025\/08\/cropped-cropped-ideindus-logo.jpg","width":1000,"height":364,"caption":"ideindus: Industrial IoT Solutions"},"image":{"@id":"https:\/\/www.ideindus.com\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/www.ideindus.com\/fr\/wp-json\/wp\/v2\/pages\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ideindus.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ideindus.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ideindus.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ideindus.com\/fr\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":119,"href":"https:\/\/www.ideindus.com\/fr\/wp-json\/wp\/v2\/pages\/282\/revisions"}],"predecessor-version":[{"id":2516,"href":"https:\/\/www.ideindus.com\/fr\/wp-json\/wp\/v2\/pages\/282\/revisions\/2516"}],"wp:attachment":[{"href":"https:\/\/www.ideindus.com\/fr\/wp-json\/wp\/v2\/media?parent=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}